{"id":17765,"date":"2025-05-29T16:27:00","date_gmt":"2025-05-29T14:27:00","guid":{"rendered":"https:\/\/clubourenseatletismo.es\/blog\/?page_id=17765"},"modified":"2026-02-10T15:23:26","modified_gmt":"2026-02-10T14:23:26","slug":"protocolo-de-proteccion-nna","status":"publish","type":"page","link":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/","title":{"rendered":"Protocolo de protecci\u00f3n NNA"},"content":{"rendered":"<p>Informaci\u00f3n sobre o\u00a0<strong>protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA)<\/strong><\/p>\n<p>Responsable de protecci\u00f3n de nenos, nenas e adolescentes:<\/p>\n<p><strong>Helena Migu\u00e9lez Sa\u00ednza<\/strong><\/p>\n<p>\u2022<a href=\"http:\/\/clubourenseatletismo.es\/blog\/wp-content\/uploads\/2026\/02\/PROTOCOLO-DE-ACOSO-CLUB-OURENSE-ATLETISMO.pdf\" target=\"_blank\" rel=\"noopener\"> Protocolo de protecci\u00f3n NNA<\/a><\/p>\n<p>\u2022 <a href=\"http:\/\/clubourenseatletismo.es\/blog\/wp-content\/uploads\/2025\/10\/Protocolo-Proteccion-NNA.pdf\" target=\"_blank\" rel=\"noopener\">Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional)<\/a><\/p>\n<p>\u2022<a href=\"escuela@clubourenseatletismo.es\" target=\"_blank\" rel=\"noopener\"> Email de denuncia<\/a><\/p>\n<p>\u2022 <a href=\"http:\/\/clubourenseatletismo.es\/blog\/wp-content\/uploads\/2025\/05\/codigo-de-conduta.pdf\" target=\"_blank\" rel=\"noopener\">C\u00f3digo de conduta<\/a><\/p>\n<p>\u2022 <a href=\"http:\/\/clubourenseatletismo.es\/blog\/wp-content\/uploads\/2025\/05\/folla-de-compromiso-entidade.pdf\" target=\"_blank\" rel=\"noopener\">Folla de compromiso &#8211; Entidade<\/a><\/p>\n<p>\u2022 <a href=\"http:\/\/clubourenseatletismo.es\/blog\/wp-content\/uploads\/2025\/05\/folla-de-compromiso-participantes.pdf\" target=\"_blank\" rel=\"noopener\">Folla de compromiso &#8211; Participantes<\/a><\/p>\n<p>\u2022 <a href=\"http:\/\/clubourenseatletismo.es\/blog\/wp-content\/uploads\/2025\/05\/autorizacion-para-actividades.pdf\" target=\"_blank\" rel=\"noopener\">Autorizaci\u00f3n para actividades<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Informaci\u00f3n sobre o\u00a0protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-17765","page","type-page","status-publish","hentry"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.1.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"Informaci\u00f3n sobre o protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla de compromiso - Entidade \u2022 Folla de compromiso - Participantes\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.1.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"es_ES\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Club Ourense Atletismo | Escuela Ourense Atletismo\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Protocolo de protecci\u00f3n NNA | Club Ourense Atletismo\" \/>\n\t\t<meta property=\"og:description\" content=\"Informaci\u00f3n sobre o protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla de compromiso - Entidade \u2022 Folla de compromiso - Participantes\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2025-05-29T14:27:00+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2026-02-10T14:23:26+00:00\" \/>\n\t\t<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/profile.php?id=100063516489280\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Protocolo de protecci\u00f3n NNA | Club Ourense Atletismo\" \/>\n\t\t<meta name=\"twitter:description\" content=\"Informaci\u00f3n sobre o protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla de compromiso - Entidade \u2022 Folla de compromiso - Participantes\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog#listItem\",\"position\":1,\"name\":\"Inicio\",\"item\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/#listItem\",\"name\":\"Protocolo de protecci\\u00f3n NNA\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/#listItem\",\"position\":2,\"name\":\"Protocolo de protecci\\u00f3n NNA\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog#listItem\",\"name\":\"Inicio\"}}]},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/#organization\",\"name\":\"Club Ourense Atletismo\",\"description\":\"Escuela Ourense Atletismo\",\"url\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/\",\"telephone\":\"+34637157458\",\"logo\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/wp-content\\\/uploads\\\/2019\\\/09\\\/cropped-LOGO-1.jpeg\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/#organizationLogo\",\"width\":512,\"height\":512},\"image\":{\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/#organizationLogo\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/profile.php?id=100063516489280\",\"https:\\\/\\\/www.instagram.com\\\/clubourenseatletismo\\\/\"]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/#webpage\",\"url\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/\",\"name\":\"Protocolo de protecci\\u00f3n NNA | Club Ourense Atletismo\",\"description\":\"Informaci\\u00f3n sobre o protocolo de protecci\\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\\u00f3n de nenos, nenas e adolescentes: Helena Migu\\u00e9lez Sa\\u00ednza \\u2022 Protocolo de protecci\\u00f3n NNA \\u2022 Comunicaci\\u00f3n de situaci\\u00f3n de violencia (formulario opcional) \\u2022 Email de denuncia \\u2022 C\\u00f3digo de conduta \\u2022 Folla de compromiso - Entidade \\u2022 Folla de compromiso - Participantes\",\"inLanguage\":\"es-ES\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/protocolo-de-proteccion-nna\\\/#breadcrumblist\"},\"datePublished\":\"2025-05-29T16:27:00+02:00\",\"dateModified\":\"2026-02-10T15:23:26+01:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/#website\",\"url\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/\",\"name\":\"Club Ourense Atletismo\",\"description\":\"Escuela Ourense Atletismo\",\"inLanguage\":\"es-ES\",\"publisher\":{\"@id\":\"https:\\\/\\\/clubourenseatletismo.es\\\/blog\\\/#organization\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Protocolo de protecci\u00f3n NNA | Club Ourense Atletismo","description":"Informaci\u00f3n sobre o protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla de compromiso - Entidade \u2022 Folla de compromiso - Participantes","canonical_url":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/","robots":"max-image-preview:large","keywords":"","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"BreadcrumbList","@id":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/clubourenseatletismo.es\/blog#listItem","position":1,"name":"Inicio","item":"https:\/\/clubourenseatletismo.es\/blog","nextItem":{"@type":"ListItem","@id":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/#listItem","name":"Protocolo de protecci\u00f3n NNA"}},{"@type":"ListItem","@id":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/#listItem","position":2,"name":"Protocolo de protecci\u00f3n NNA","previousItem":{"@type":"ListItem","@id":"https:\/\/clubourenseatletismo.es\/blog#listItem","name":"Inicio"}}]},{"@type":"Organization","@id":"https:\/\/clubourenseatletismo.es\/blog\/#organization","name":"Club Ourense Atletismo","description":"Escuela Ourense Atletismo","url":"https:\/\/clubourenseatletismo.es\/blog\/","telephone":"+34637157458","logo":{"@type":"ImageObject","url":"https:\/\/clubourenseatletismo.es\/blog\/wp-content\/uploads\/2019\/09\/cropped-LOGO-1.jpeg","@id":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/#organizationLogo","width":512,"height":512},"image":{"@id":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/#organizationLogo"},"sameAs":["https:\/\/www.facebook.com\/profile.php?id=100063516489280","https:\/\/www.instagram.com\/clubourenseatletismo\/"]},{"@type":"WebPage","@id":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/#webpage","url":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/","name":"Protocolo de protecci\u00f3n NNA | Club Ourense Atletismo","description":"Informaci\u00f3n sobre o protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla de compromiso - Entidade \u2022 Folla de compromiso - Participantes","inLanguage":"es-ES","isPartOf":{"@id":"https:\/\/clubourenseatletismo.es\/blog\/#website"},"breadcrumb":{"@id":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/#breadcrumblist"},"datePublished":"2025-05-29T16:27:00+02:00","dateModified":"2026-02-10T15:23:26+01:00"},{"@type":"WebSite","@id":"https:\/\/clubourenseatletismo.es\/blog\/#website","url":"https:\/\/clubourenseatletismo.es\/blog\/","name":"Club Ourense Atletismo","description":"Escuela Ourense Atletismo","inLanguage":"es-ES","publisher":{"@id":"https:\/\/clubourenseatletismo.es\/blog\/#organization"}}]},"og:locale":"es_ES","og:site_name":"Club Ourense Atletismo | Escuela Ourense Atletismo","og:type":"article","og:title":"Protocolo de protecci\u00f3n NNA | Club Ourense Atletismo","og:description":"Informaci\u00f3n sobre o protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla de compromiso - Entidade \u2022 Folla de compromiso - Participantes","og:url":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/","article:published_time":"2025-05-29T14:27:00+00:00","article:modified_time":"2026-02-10T14:23:26+00:00","article:publisher":"https:\/\/www.facebook.com\/profile.php?id=100063516489280","twitter:card":"summary","twitter:title":"Protocolo de protecci\u00f3n NNA | Club Ourense Atletismo","twitter:description":"Informaci\u00f3n sobre o protocolo de protecci\u00f3n de nenos, nenas e adolescentes (NNA) Responsable de protecci\u00f3n de nenos, nenas e adolescentes: Helena Migu\u00e9lez Sa\u00ednza \u2022 Protocolo de protecci\u00f3n NNA \u2022 Comunicaci\u00f3n de situaci\u00f3n de violencia (formulario opcional) \u2022 Email de denuncia \u2022 C\u00f3digo de conduta \u2022 Folla de compromiso - Entidade \u2022 Folla de compromiso - Participantes"},"aioseo_meta_data":{"post_id":"17765","title":null,"description":null,"keywords":null,"keyphrases":{"focus":{"keyphrase":"Protocolo de protecci\u00f3n NNA","score":82,"analysis":{"keyphraseInTitle":{"score":9,"maxScore":9,"error":0},"keyphraseInDescription":{"score":9,"maxScore":9,"error":0},"keyphraseLength":{"score":6,"maxScore":9,"error":1,"length":5},"keyphraseInURL":{"score":5,"maxScore":5,"error":0},"keyphraseInIntroduction":{"score":3,"maxScore":9,"error":1},"keyphraseInSubHeadings":[],"keyphraseInImageAlt":[],"keywordDensity":{"type":"best","score":9,"maxScore":9,"error":0}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":null,"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"WebPage","isEnabled":true},"graphs":[]},"schema_type":"default","schema_type_options":null,"pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","location":null,"local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":{"faqs":[],"keyPoints":[],"titles":[],"descriptions":[],"socialPosts":{"email":[],"linkedin":[],"twitter":[],"facebook":[],"instagram":[]}},"created":"2025-05-27 13:16:38","updated":"2026-02-10 14:23:26","seo_analyzer_scan_date":null,"focus_keyword":"Protocolo de protecci\u00f3n NNA","additional_keywords":null,"truseo_locale":null},"aioseo_breadcrumb":"<div class=\"aioseo-breadcrumbs\"><span class=\"aioseo-breadcrumb\">\n\t\t\t<a href=\"https:\/\/clubourenseatletismo.es\/blog\" title=\"Inicio\">Inicio<\/a>\n\t\t<\/span><span class=\"aioseo-breadcrumb-separator\">&raquo;<\/span><span class=\"aioseo-breadcrumb\">\n\t\t\tProtocolo de protecci\u00f3n NNA\n\t\t<\/span><\/div>","aioseo_breadcrumb_json":[{"label":"Inicio","link":"https:\/\/clubourenseatletismo.es\/blog"},{"label":"Protocolo de protecci\u00f3n NNA","link":"https:\/\/clubourenseatletismo.es\/blog\/protocolo-de-proteccion-nna\/"}],"_links":{"self":[{"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/pages\/17765","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/comments?post=17765"}],"version-history":[{"count":5,"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/pages\/17765\/revisions"}],"predecessor-version":[{"id":18147,"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/pages\/17765\/revisions\/18147"}],"wp:attachment":[{"href":"https:\/\/clubourenseatletismo.es\/blog\/wp-json\/wp\/v2\/media?parent=17765"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}